{"id":181,"date":"2024-08-14T09:14:58","date_gmt":"2024-08-14T07:14:58","guid":{"rendered":"http:\/\/preview.abc4it.com\/gospelchor_kilchberg\/?page_id=181"},"modified":"2025-11-24T18:52:13","modified_gmt":"2025-11-24T17:52:13","slug":"vergangene-auftritte","status":"publish","type":"page","link":"https:\/\/gospelchor-kilchberg.ch\/cms\/auftritte\/vergangene-auftritte\/","title":{"rendered":"Vergangene Auftritte"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"181\" class=\"elementor elementor-181\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8394e e-flex e-con-boxed e-con e-parent\" data-id=\"2b8394e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f2cd7 elementor-widget elementor-widget-spacer\" data-id=\"a0f2cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0336f elementor-widget elementor-widget-heading\" data-id=\"9a0336f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vergangene Auftritte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6ddff5 e-flex e-con-boxed e-con e-parent\" data-id=\"b6ddff5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bd9c06a e-con-full e-flex e-con e-child\" data-id=\"bd9c06a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a97e22 elementor-widget elementor-widget-text-editor\" data-id=\"8a97e22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #3366ff;\">2025<\/span><\/h3><p><em>Samstag 8. &amp; 15 November 2015<\/em><br \/>Jahreskonzerte \u00abHand in Hand\u00bb in der ref. Kirche Kilchberg<\/p><p><em>Sonntag, 6. Juli 2025<br \/><\/em>Mitwirkung im Gottesdienst in der ref. Kirche Kilchberg und Auftritt beim &#8222;Sommerreigen&#8220;<\/p><p><em>Sonntag, 6. April 2025<br \/><\/em>Mitwirkung im Abendgottesdienst in der ref. Kirche Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2024<\/span><\/h3><p><em>Sonntag, 15. Dezember 2024<br \/><\/em>Auftritte im Emilienheim und Alterszentrum Hochweid<\/p><p><em>Samstag, 9. November 2024<\/em><br \/>2. Jahreskonzert \u00abCome Let Us Sing\u00bb ref. Kirche Kilchberg<\/p><p><em>Samstag, 16. November 2024<\/em><br \/>1. Jahreskonzert \u00abCome Let Us Sing\u00bb ref. Kirche Kilchberg<\/p><p><em>Sonntag, 8. September 2024<\/em><br \/>Mitwirken im Abendgottesdienst in der ref. Kirche Kilchberg<\/p><p><em>Sonntag, 4. Februar 2024<\/em><br \/>Mitwirken im Gottesdienst in der ref. Kirche Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2023<\/span><\/h3><p><em>Sonntag, 26. M\u00e4rz 2023<\/em><br \/>Mitwirken im Abendgottesdienst in der ref. Kirche Kilchberg<\/p><p><em>Samstag, 11. November 2023<\/em><br \/>1. Jahreskonzert \u00abRoyal Telephone\u00bb ref. Kirche Kilchberg<\/p><p><em>Samstag, 18. November 2023<\/em><br \/>2. Jahreskonzert \u00abRoyal Telephone\u00bb ref. Kirche Kilchberg<\/p><p><em>Sonntag 17, Dezember 2023<\/em><br \/>Singen im Alterszentrum und Emilienheim<\/p><h3><span style=\"color: #3366ff;\">2022<\/span><\/h3><p><em>Sonntag, 11. Dezember 2022<\/em><br \/>Auftritte im Emilienheim und Alterszentrum Hochweid<\/p><p><em>Sonntag, 20. November 2022<\/em><br \/>Mitwirkung im Gottesdienst ref. Kirche Kilchberg<\/p><p><em>Samstag, 12. November 2022<\/em><br \/>1. Jahreskonzert \u00abCome Let Us Sing\u00bb ref. Kirche Kilchberg<\/p><p><em>Samstag, 29. Oktober 2022<\/em><br \/>2. Jahreskonzert \u00abCome Let Us Sing\u00bb ref. Kirche Kilchberg<\/p><p><em>Sonntag, 15. Mai 2022<\/em><br \/>Mitwirkung im Gottesdienst ref. Kirche Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2021 \/ 2020<\/span><\/h3><p><em>Sonntag, 7. November 2021<\/em><br \/>Singen im Gottesdienst in der ref. Kirche Kilchberg<\/p><p><em><span style=\"color: #3366ff;\">Keine andern Veranstaltungen wegen Corona<\/span><\/em><\/p><h3><span style=\"color: #3366ff;\">2019<\/span><\/h3><p><em>Sonntag, 19. Mai 2019<\/em><br \/>Mitwirkung im Abend-Gottesdienst ref. Kirche Kilchberg<\/p><p><em>Samstag, 26. Oktober 2019<\/em><br \/>1. Jahreskonzert \u00abOh, What a Time!\u00bb ref. Kirche Kilchberg<\/p><p><em>Samstag, 9. November 2019<\/em><br \/>2. Jahreskonzert \u00abOh, What a Time!\u00bb ref. Kirche Kilchberg<\/p><p><em>Sonntag, 1. Dezember 2019<\/em><br \/>Mitwirkung im Gottesdienst ref. Kirche Kilchberg<\/p><p><em>Sonntag, 15. Dezember 2019<\/em><br \/>Auftritt im Emilienheim Kilchberg<br \/>Auftritt im Alterszentrum Hochweid Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2018<\/span><\/h3><p><em>Sonntag, 16. Dezember 2018<\/em><br \/>Auftritt im Emilienheim Kilchberg<\/p><p><em>Sonntag, 25. November 2018<\/em><br \/>Mitwirkung im Gottesdienst ref. Kirche Kilchberg<br \/>Auftritt im Alterszentrum Hochweid<\/p><p><em>Samstag, 10. November 2018<\/em><br \/>2. Jahreskonzert \u00abA Place in the Choir\u00bb ref. Kirche Kilchberg<\/p><p><em>Samstag, 27. Oktober 2018<\/em><br \/>1. Jahreskonzert \u00abA Place in the Choir\u00bb ref. Kirche Kilchberg<\/p><p><em>Sonntag, 2. September 2018<\/em><br \/>Mitwirkung im Gottesdienst ref. Kirche Kilchberg<\/p><p><em>Sonntag, 8. Juli 2018<\/em><br \/>Mitsingen im Abendgottesdienst ref. Kirche Kilchberg<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fb3611 e-con-full e-flex e-con e-child\" data-id=\"1fb3611\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07462c4 elementor-widget elementor-widget-text-editor\" data-id=\"07462c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #3366ff;\">2017<\/span><\/h3><p><em>Sonntag, 17. Dezember 2017<\/em><br \/>Mitwirkung im Abendgottesdienst ref. Kirche Kilchberg<br \/>Auftritt im Emilienheim Kilchberg<\/p><p><em>Sonntag, 3. Dezember 2017<\/em><br \/>Auftritt im Alterszentrum Hochweid<\/p><p><em>Samstag, 2. Dezember 2017<\/em><br \/>Mitwirkung beim Benefizkonzert \u00abBildung. Eine Chance f\u00fcr Kinder in Not\u00bb im Pianohaus Schoeckle Thalwil<\/p><p><em>Samstag, 11. November 2017<\/em><br \/>\u00abGet on Board\u00bb 2. Jubil\u00e4umkonzert 10 Jahre Gospelchor Kilchberg in der Ref. Kirche Kilchberg<\/p><p><em>Samstag, 28. Oktober 2017<\/em><br \/>\u00abGet on Board\u00bb 1. Jubil\u00e4umkonzert 10 Jahre Gospelchor Kilchberg in der Ref. Kirche Kilchberg<\/p><p><em>Sonntag, 27. August 2017<\/em><br \/>Mitwirkung im Gottesdienst am Stockenfest<\/p><h3><span style=\"color: #3366ff;\">2016<\/span><\/h3><p><em>Sonntag, 11. Dezember 2016<\/em><br \/>Mitwirkung im Gottesdienst in der ref. Kirche Kilchberg<br \/>Auftritt im Emilienheim Kilchberg<\/p><p><em>Samstag 29. Oktober und Samstag 12. November 2016<\/em><br \/>Jahreskonzerte \u00abMiracles\u00bb in der ref. Kirche Kilchberg<\/p><p><em>Sonntag, 27. November 2016<\/em><br \/>Auftritt im Alterszentrum Hochweid Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2015<\/span><\/h3><p><em>Sonntag, 13. Dezember 2015<\/em><br \/>Auftritt im Alterszentrum Hochweid Kilchberg<\/p><p><em>Sonntag, 29. November 2015<\/em><br \/>Mitwirkung im Gottesdienst in der katholischen Kirche Kilchberg<br \/>Auftritt im Emilienheim Kilchberg<\/p><p><em>Samstag, 7. November 2015<\/em><br \/>2. Jahreskonzert \u00abA Living Prayer\u00bb in der ref. Kirche Thalwil<\/p><p><em>Samstag, 24. Oktober 2015<\/em><br \/>1. Jahreskonzert \u00abA Living Prayer\u00bb in der Kirche Kilchberg<\/p><p><em>Sonntag, 5. Juli 2015<\/em><br \/>Mitwirkung im Gottesdienst in der ref. Kirche Kilchberg<\/p><p><em>Samstag, 13. Juni 2015<\/em><br \/>Mitwirkung an einer Hochzeit in der ref. Kirche Kilchberg<\/p><p><em>Samstag, 30. Mai 2015<\/em><br \/>Mitwirkung an einer Hochzeit im Kulturmarkt Z\u00fcrich<\/p><h3><span style=\"color: #3366ff;\">2014<\/span><\/h3><p><em>Sonntag, 14. Dezember 2014<\/em><br \/>Auftritt im Emilienheim Kilchberg<\/p><p><em>Sonntag, 14. Dezember 2014<\/em><br \/>Mitwirkung im Gottesdienst in der reformierten Kirche Kilchberg<\/p><p><em>Sonntag, 23. November 2014<\/em><br \/>Auftritt im Alterzentrum Hochweid Kilchberg<\/p><p><em>Freitag, 7. November 2014<\/em><br \/>2. Jahreskonzert \u00abTurn! Turn! Turn!\u00bb in der reformierten Kirche R\u00fcschlikon<\/p><p><em>Samstag, 25. Oktober 2014<\/em><br \/>1. Jahreskonzert \u00abTurn! Turn! Turn!\u00bb in der Kirche Kilchberg<\/p><p><em>Dienstag, 18. M\u00e4rz 2014<\/em><br \/>Gospel-Konzert f\u00fcr den Schaffhauser-Verein in der Kirche Kilchberg<\/p><h3><span style=\"color: #3366ff;\">2013<\/span><\/h3><p><em>Sonntag, 15. Dezember 2013<\/em><br \/>Singen im Emilienheim Kilchberg<\/p><p><em>Sonntag, 15. Dezember 2013<\/em><br \/>Singen im Gottesdienst in der Kirche Kilchberg<\/p><p><em>Sonntag, 1. Dezember 2013<\/em><br \/>Singen im Alterszentrum Kilchberg<\/p><p><em>Samstag, 9. November 2013<\/em><br \/>2. Jahreskonzert \u00abIn His Hands\u00bb in der Kirche Kilchberg<\/p><p><em>Samstag, 26. Oktober 2013<\/em><br \/>1. Jahreskonzert \u00abIn His Hands\u00bb in der Kirche Kilchberg<\/p><p><em>Sonntag, 25. August 2013<\/em><br \/>Singen im \u00f6kumenischen Gottesdienst am Stockenfest<\/p><p><em>Sonntag, 7. Juli 2013<\/em><br \/>Singen im Abschiedsgottesdienst von Pfrn. Adelheid Jewanski, Kirche Kilchberg<\/p><p><em>Freitag, 28. Juni 2013<\/em><br \/>Singen im Jugendgottesdienst Kirche R\u00fcschlikon<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vergangene Auftritte 2025 Samstag 8. &amp; 15 November 2015Jahreskonzerte \u00abHand in Hand\u00bb in der ref. Kirche Kilchberg Sonntag, 6. Juli 2025Mitwirkung im Gottesdienst in der ref. Kirche Kilchberg und Auftritt beim &#8222;Sommerreigen&#8220; Sonntag, 6. April 2025Mitwirkung im Abendgottesdienst in der ref. Kirche Kilchberg 2024 Sonntag, 15. Dezember 2024Auftritte im Emilienheim und Alterszentrum Hochweid Samstag, 9.&hellip;&nbsp;<a href=\"https:\/\/gospelchor-kilchberg.ch\/cms\/auftritte\/vergangene-auftritte\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Vergangene Auftritte<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":86,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","h5ap_radio_sources":[],"footnotes":""},"class_list":["post-181","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/pages\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":61,"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/pages\/181\/revisions"}],"predecessor-version":[{"id":1015,"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/pages\/181\/revisions\/1015"}],"up":[{"embeddable":true,"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/pages\/86"}],"wp:attachment":[{"href":"https:\/\/gospelchor-kilchberg.ch\/cms\/wp-json\/wp\/v2\/media?parent=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}